{"id":915,"date":"2022-05-15T22:02:39","date_gmt":"2022-05-15T22:02:39","guid":{"rendered":"https:\/\/elrotativo.mx\/portal\/?p=915"},"modified":"2022-05-15T22:02:42","modified_gmt":"2022-05-15T22:02:42","slug":"gobierno-va-contra-la-narcocultura-gutierrez-luna","status":"publish","type":"post","link":"https:\/\/elrotativo.com.mx\/portal\/gobierno-va-contra-la-narcocultura-gutierrez-luna\/","title":{"rendered":"Gobierno va contra la narcocultura; Guti\u00e9rrez Luna"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Orizaba, ver.- En el tema de la atenci\u00f3n a la inseguridad se le debe dar otra dimensi\u00f3n, pues hoy en d\u00eda prevalece una narcocultura en donde los j\u00f3venes aspiran a ser criminales, lament\u00f3 el presidente de la C\u00e1mara de Diputados, Sergio Guti\u00e9rrez Luna.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entrevistado en su visita a la ciudad de Orizaba en donde particip\u00f3 en una gira de trabajo, expuso que el presidente L\u00f3pez Obrador todos los d\u00edas tiene reuniones, en busca de busca estrategias para acabar con el tema de la inseguridad, pero lo real es que hay una cultura entre los j\u00f3venes, para obtener beneficios a trav\u00e9s de hechos il\u00edcitos, por lo que es ah\u00ed en donde est\u00e1n trabajando para mostrar a los j\u00f3venes que tienen m\u00e1s oportunidades fuera de la delincuencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abHay problem\u00e1ticas que tienen que ver con pol\u00edtica criminal en las que se est\u00e1 trabajando, pero la parte que nos preocupa a nosotros es el caldo de cultivo de j\u00f3venes. Necesitamos que tengan otra oportunidad, que no engrosen las filas de la delincuencia\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lament\u00f3 que mientras los j\u00f3venes no busquen otro futuro, se tendr\u00e1 un c\u00edrculo vicioso como el que est\u00e1 dejando este problema que no es de ahorita, sino que tiene 15 o 18 a\u00f1os; \u201choy en d\u00eda a los ni\u00f1os de secundaria les preguntan qu\u00e9 quieren ser de grande y responden que sicario; cambiar esa mentalidad no es inmediato, pero s\u00ed se est\u00e1 trabajando\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agreg\u00f3 que las narcoseries e informaci\u00f3n a la que acceden los j\u00f3venes nutren la idea de que esa puede ser una ruta, adem\u00e1s de que el contenido televisivo no abona cuando se tiene una realidad como la de M\u00e9xico, por lo que se debe buscar restringirlo para que los j\u00f3venes no idealicen este tipo de vida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Orizaba, ver.- En el tema de la atenci\u00f3n a la inseguridad se le debe dar otra dimensi\u00f3n, pues hoy en d\u00eda prevalece una narcocultura en donde los j\u00f3venes aspiran a ser criminales, lament\u00f3 el presidente de la C\u00e1mara de Diputados, Sergio Guti\u00e9rrez Luna. Entrevistado en su visita a la ciudad de Orizaba en donde particip\u00f3 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":916,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[26,10],"tags":[],"class_list":["post-915","post","type-post","status-publish","format-standard","has-post-thumbnail","category-destacada-4","category-local-regional"],"_links":{"self":[{"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/posts\/915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=915"}],"version-history":[{"count":1,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/posts\/915\/revisions"}],"predecessor-version":[{"id":917,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/posts\/915\/revisions\/917"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/media\/916"}],"wp:attachment":[{"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}