{"id":912,"date":"2022-05-15T21:58:10","date_gmt":"2022-05-15T21:58:10","guid":{"rendered":"https:\/\/elrotativo.mx\/portal\/?p=912"},"modified":"2022-05-15T21:58:12","modified_gmt":"2022-05-15T21:58:12","slug":"descarrilamiento-en-puebla-afecto-trafico-de-trenes-por-una-semana","status":"publish","type":"post","link":"https:\/\/elrotativo.com.mx\/portal\/descarrilamiento-en-puebla-afecto-trafico-de-trenes-por-una-semana\/","title":{"rendered":"Descarrilamiento en Puebla, afect\u00f3 tr\u00e1fico de trenes por una semana"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>*Pobladores bloquearon v\u00edas para exigir un pozo de agua<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Orizaba, Ver.- A una semana del descarrilamiento del ferrocarril en el t\u00fanel numero 4 denominado \u201cMexicano\u201d de la l\u00ednea que conduce de Veracruz a la Ciudad de M\u00e9xico, el tr\u00e1fico de trenes se podr\u00eda retomar este fin de semana, luego de que habitantes mantuvieran un bloqueo en exigencia de obra p\u00fablica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y es que el pasado s\u00e1bado las tolvas cargadas con m\u00e1s de 100 &nbsp;toneladas de frijol, se descarrilaron recorriendo en estas condiciones m\u00e1s de tres kil\u00f3metros, quedando a la altura de dicho puente, por lo que al arribar el personal de Ferrosur para hacer las reparaciones correspondientes, los &nbsp;pobladores de la zona aleda\u00f1a de un municipio de Puebla no los dejaron laborar bloqueando adem\u00e1s el tr\u00e1fico de trenes, pues exig\u00edan que la empresa les ayudara a edificar un pozo para dotarles de agua potable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre este tema se cuestion\u00f3 al secretario general de la Secci\u00f3n 20 del Sindicato de Trabajadores Ferrocarrileros de la Rep\u00fablica Mexicana (STFRM), Hermilo Merino Bello quien expuso que los pobladores de una comunidad del estado de Puebla cercana a Ca\u00f1ada, bloquearon por espacio de siete d\u00edas la circulaci\u00f3n del ferrocarril afectando tanto a la empresa como al personal al dejar de darse el movimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque enfatiz\u00f3 que el descarrilamiento se debi\u00f3 a una falla mec\u00e1nica y no a un sabotaje, reconoci\u00f3 que el paso del ferrocarril se mantuvo pausado por una semana a pesar de que la solicitud del pueblo es una situaci\u00f3n ajena a la empresa, pues los que deben darle ese servicio son el Ayuntamiento o en todo caso el Gobierno del Estado, adem\u00e1s de que los ferrocarriles s\u00f3lo pasan por el lugar, no hacen uso del vital l\u00edquido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, dijo que con la finalidad de buscar un acuerdo se reunieron con los pobladores y autoridades del vecino estado logrando acuerdos que permitieron al personal de Ferrosur hacer las reparaciones necesarias y as\u00ed este domingo se pueda reanudar las corridas de ese transporte de carga.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>*Pobladores bloquearon v\u00edas para exigir un pozo de agua Orizaba, Ver.- A una semana del descarrilamiento del ferrocarril en el t\u00fanel numero 4 denominado \u201cMexicano\u201d de la l\u00ednea que conduce de Veracruz a la Ciudad de M\u00e9xico, el tr\u00e1fico de trenes se podr\u00eda retomar este fin de semana, luego de que habitantes mantuvieran un bloqueo [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":913,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[25,10],"tags":[],"class_list":["post-912","post","type-post","status-publish","format-standard","has-post-thumbnail","category-destacada-1","category-local-regional"],"_links":{"self":[{"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/posts\/912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=912"}],"version-history":[{"count":1,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/posts\/912\/revisions"}],"predecessor-version":[{"id":914,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/posts\/912\/revisions\/914"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/media\/913"}],"wp:attachment":[{"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}