{"id":4829,"date":"2022-08-10T00:52:08","date_gmt":"2022-08-10T05:52:08","guid":{"rendered":"https:\/\/elrotativo.mx\/portal\/?p=4829"},"modified":"2022-08-10T00:52:10","modified_gmt":"2022-08-10T05:52:10","slug":"fallecio-jose-mauro-el-gigante-de-acultzingo","status":"publish","type":"post","link":"https:\/\/elrotativo.com.mx\/portal\/fallecio-jose-mauro-el-gigante-de-acultzingo\/","title":{"rendered":"Falleci\u00f3 Jos\u00e9 Mauro el \u201cGigante de Acultzingo\u201d"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>*Por complicaciones de su enfermedad<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Acultzingo, Ver.- A la edad de 30 a\u00f1os, este martes, falleci\u00f3 el joven Jos\u00e9 Mauro Romero Hern\u00e1ndez quien era conocido como \u00abEl gigante de Acultzingo\u00bb, al parecer por complicaciones de su enfermedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El habitante de la localidad de Pinotla, municipio de Acultzingo, padec\u00eda una enfermedad de la tiroides que le caus\u00f3 un crecimiento desmedido, por lo que lleg\u00f3 a alcanzar la altura de 2,25 metros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante su juventud, el ahora extinto se dedic\u00f3 a la alba\u00f1iler\u00eda, as\u00ed como al campo, pero debido a complicaciones de salud ya no pudo realizar trabajos y se trasladaba a la ciudad de Orizaba a pedir apoyo econ\u00f3mico a los transe\u00fantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque fue apoyado por instituciones sociales, algunos personajes pol\u00edticos y del ayuntamiento de Acultzingo, no recibi\u00f3 la ayuda m\u00e9dica adecuada para su enfermedad, por lo que este martes 9 de agosto perdi\u00f3 la vida en su domicilio en la comunidad de Pinotla en donde ahora le sobreviven cinco hermanos y su madre, Julia Hern\u00e1ndez Rosas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>*Por complicaciones de su enfermedad Acultzingo, Ver.- A la edad de 30 a\u00f1os, este martes, falleci\u00f3 el joven Jos\u00e9 Mauro Romero Hern\u00e1ndez quien era conocido como \u00abEl gigante de Acultzingo\u00bb, al parecer por complicaciones de su enfermedad. El habitante de la localidad de Pinotla, municipio de Acultzingo, padec\u00eda una enfermedad de la tiroides que le [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":4830,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[10],"tags":[],"class_list":["post-4829","post","type-post","status-publish","format-standard","has-post-thumbnail","category-local-regional"],"_links":{"self":[{"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/posts\/4829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=4829"}],"version-history":[{"count":1,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/posts\/4829\/revisions"}],"predecessor-version":[{"id":4831,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/posts\/4829\/revisions\/4831"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/media\/4830"}],"wp:attachment":[{"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=4829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=4829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=4829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}