{"id":12259,"date":"2023-01-30T23:36:35","date_gmt":"2023-01-31T05:36:35","guid":{"rendered":"https:\/\/elrotativo.mx\/portal\/?p=12259"},"modified":"2023-01-30T23:36:36","modified_gmt":"2023-01-31T05:36:36","slug":"detiene-ssp-a-dos-por-distintos-delitos-en-tihuatlan","status":"publish","type":"post","link":"https:\/\/elrotativo.com.mx\/portal\/detiene-ssp-a-dos-por-distintos-delitos-en-tihuatlan\/","title":{"rendered":"<strong>Detiene SSP a dos por distintos delitos en Tihuatl\u00e1n<\/strong>"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Xalapa, Ver.- Dos personas fueron detenidas por elementos de la Secretar\u00eda de Seguridad P\u00fablica (SSP), a trav\u00e9s de Polic\u00eda Estatal por presunta portaci\u00f3n ilegal de arma de fuego y conducir un veh\u00edculo con reporte de robo en el municipio de Tihuatl\u00e1n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Oficiales estatales realizaban recorridos en la carretera Canoas &#8211; Mart\u00ednez de la Torre, perteneciente a Tihuatl\u00e1n, cuando detectaron a un sujeto a bordo de un veh\u00edculo Honda, placas PBB7546.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Acto seguido, le realizaron a Miguel de Jes\u00fas \u201cN\u201d una revisi\u00f3n y le encontraron un arma de fuego corta, un cargador y cartuchos \u00fatiles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, en la colonia Centro fue ubicado Leobardo \u201cN\u201d, a bordo de una motocicleta Italika, sin placas y con reporte de robo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los detenidos y lo asegurado fue puesto a disposici\u00f3n de la autoridad correspondiente, para los tr\u00e1mites que marca la ley.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Xalapa, Ver.- Dos personas fueron detenidas por elementos de la Secretar\u00eda de Seguridad P\u00fablica (SSP), a trav\u00e9s de Polic\u00eda Estatal por presunta portaci\u00f3n ilegal de arma de fuego y conducir un veh\u00edculo con reporte de robo en el municipio de Tihuatl\u00e1n. Oficiales estatales realizaban recorridos en la carretera Canoas &#8211; Mart\u00ednez de la Torre, perteneciente [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12246,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[7],"tags":[],"class_list":["post-12259","post","type-post","status-publish","format-standard","has-post-thumbnail","category-policiaca"],"_links":{"self":[{"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/posts\/12259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=12259"}],"version-history":[{"count":1,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/posts\/12259\/revisions"}],"predecessor-version":[{"id":12260,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/posts\/12259\/revisions\/12260"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/media\/12246"}],"wp:attachment":[{"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=12259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=12259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=12259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}