{"id":10048,"date":"2022-12-08T23:19:33","date_gmt":"2022-12-09T05:19:33","guid":{"rendered":"https:\/\/elrotativo.mx\/portal\/?p=10048"},"modified":"2022-12-08T23:19:34","modified_gmt":"2022-12-09T05:19:34","slug":"dejan-manta-con-amenazas-y-bolsas-negras-con-restos-de-animales","status":"publish","type":"post","link":"https:\/\/elrotativo.com.mx\/portal\/dejan-manta-con-amenazas-y-bolsas-negras-con-restos-de-animales\/","title":{"rendered":"<strong>Dejan manta con amenazas y bolsas negras con restos de animales<\/strong>"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Zongolica, Ver.- Una narcomanta y bolsas pl\u00e1sticas en color negro con restos de animales, fueron dejadas en la carretera Zongolica-Comalapa la madrugada de este 8 de diciembre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fueron pobladores de la zona quienes dieron aviso a las corporaciones policiacas, las cuales se movilizaron al lugar y procedieron a acordonar la zona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A su llegada los elementos policiacos procedieron a resguardar la zona mientras esperaban el arribo de peritos en criminal\u00edstica quienes revisaron el contenido de las bolsas y descartaron se tratara de restos humanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las bolsas fueron encontradas cerca de la orilla de la carretera al pie de un letrero del que se colg\u00f3 la narcomanta, la cual denost\u00f3 a un jefe policiaco y anunci\u00f3 una \u201climpia\u201d en el municipio de Zongolica, por lo que tambi\u00e9n autoridades de la Fiscal\u00eda tomaron conocimiento del hecho.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Zongolica, Ver.- Una narcomanta y bolsas pl\u00e1sticas en color negro con restos de animales, fueron dejadas en la carretera Zongolica-Comalapa la madrugada de este 8 de diciembre. Fueron pobladores de la zona quienes dieron aviso a las corporaciones policiacas, las cuales se movilizaron al lugar y procedieron a acordonar la zona. A su llegada los [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10022,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"tdm_status":"","tdm_grid_status":"","footnotes":""},"categories":[7],"tags":[],"class_list":["post-10048","post","type-post","status-publish","format-standard","has-post-thumbnail","category-policiaca"],"_links":{"self":[{"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/posts\/10048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/comments?post=10048"}],"version-history":[{"count":1,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/posts\/10048\/revisions"}],"predecessor-version":[{"id":10049,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/posts\/10048\/revisions\/10049"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/media\/10022"}],"wp:attachment":[{"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/media?parent=10048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/categories?post=10048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elrotativo.com.mx\/portal\/wp-json\/wp\/v2\/tags?post=10048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}